{"id":32602,"date":"2025-01-08T10:33:29","date_gmt":"2025-01-08T13:33:29","guid":{"rendered":"https:\/\/radiostudiow.com.br\/site\/?p=32602"},"modified":"2025-01-31T14:57:59","modified_gmt":"2025-01-31T17:57:59","slug":"secretaria-da-saude-alerta-para-cuidados-com-animais-peconhentos-durante-o-verao","status":"publish","type":"post","link":"https:\/\/radiostudiow.com.br\/site\/2025\/01\/08\/secretaria-da-saude-alerta-para-cuidados-com-animais-peconhentos-durante-o-verao\/","title":{"rendered":"Secretaria da Sa\u00fade alerta para cuidados com animais pe\u00e7onhentos durante o ver\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Secretaria de Estado da Sa\u00fade (Sesa) faz um alerta \u00e0 popula\u00e7\u00e3o sobre o risco de acidentes com animais pe\u00e7onhentos, tanto terrestres quanto aqu\u00e1ticos, comuns nessa \u00e9poca do ano, de temperaturas mais altas. O per\u00edodo entre dezembro e mar\u00e7o, marcado pela maior movimenta\u00e7\u00e3o de pessoas em regi\u00f5es tur\u00edsticas, de mata e Litoral, coincide com o aumento do metabolismo e do deslocamento desses animais, motivados pela busca de alimento e reprodu\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"897\" height=\"204\" src=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2024\/04\/image-50.png\" alt=\"\" class=\"wp-image-21368\" srcset=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2024\/04\/image-50.png 897w, https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2024\/04\/image-50-300x68.png 300w, https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2024\/04\/image-50-768x175.png 768w\" sizes=\"auto, (max-width: 897px) 100vw, 897px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para evitar acidentes com animais como cobras, escorpi\u00f5es, aranhas e lagartas, a Sesa recomenda a ado\u00e7\u00e3o de medidas simples, mas fundamentais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em atividades ao ar livre, como trilhas, jardinagem e passeios em \u00e1reas de mata, \u00e9 essencial utilizar equipamentos de prote\u00e7\u00e3o individual (EPIs), como botas e luvas. Al\u00e9m disso, as pessoas devem ficar atentas aos locais onde h\u00e1 risco de presen\u00e7a desses animais, como buracos no ch\u00e3o, ocos de \u00e1rvores, montes de lenha e pedras. \u00c9 preciso evitar tocar diretamente nesses locais. Roupas, cal\u00e7ados, toalhas e roupas de cama tamb\u00e9m devem ser sempre inspecionados antes do uso.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-29.png\" alt=\"\" class=\"wp-image-32605\" srcset=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-29.png 1024w, https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-29-300x200.png 300w, https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-29-768x512.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Em casa, afastar camas e ber\u00e7os das paredes e evitar que len\u00e7\u00f3is encostem no ch\u00e3o s\u00e3o medidas simples e ajudam a evitar que aranhas e escorpi\u00f5es subam nas superf\u00edcies. Caso a pessoa encontro algum animal pe\u00e7onhento, a orienta\u00e7\u00e3o \u00e9 afastar-se com cuidado, sem toc\u00e1-lo ou assust\u00e1-lo, e acionar profissionais competentes, como bombeiros, pol\u00edcia ambiental ou a vigil\u00e2ncia de zoonoses.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-28.png\" alt=\"\" class=\"wp-image-32604\" srcset=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-28.png 1024w, https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-28-300x200.png 300w, https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-28-768x512.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LAGARTAS&nbsp;<\/strong>\u2013<strong>&nbsp;<\/strong>Ap\u00f3s um longo per\u00edodo sem registros, neste m\u00eas foi notificado um acidente grave envolvendo a lagarta do g\u00eanero&nbsp;<em>Lonomia<\/em>. O contato com ela pode causar uma s\u00edndrome hemorr\u00e1gica grave, potencialmente fatal se n\u00e3o tratada adequadamente. Essas lagartas vivem em col\u00f4nias, e o contato com v\u00e1rios indiv\u00edduos ao mesmo tempo pode intensificar a exposi\u00e7\u00e3o ao veneno.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-27.png\" alt=\"\" class=\"wp-image-32603\" srcset=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-27.png 1024w, https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-27-300x200.png 300w, https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2025\/01\/image-27-768x512.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA popula\u00e7\u00e3o precisa estar atenta, especialmente em \u00e1reas arborizadas, onde essas lagartas costumam se alojar. \u00c9 importante observar antes de tocar em troncos de \u00e1rvores ou se encostar, pois o contato com as Lonomias pode ter consequ\u00eancias graves. Em caso de acidente, a recomenda\u00e7\u00e3o \u00e9 procurar imediatamente um servi\u00e7o de sa\u00fade para receber o tratamento adequado\u201d, alertou a bi\u00f3loga da Divis\u00e3o de Vigil\u00e2ncia de Zoonoses e Intoxica\u00e7\u00f5es da Sesa, Juliana Cequinel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ANIMAIS AQU\u00c1TICOS<\/strong>&nbsp;\u2013&nbsp;Nos ambientes aqu\u00e1ticos, o risco de acidentes \u00e9 elevado principalmente por \u00e1guas-vivas, caravelas, ouri\u00e7os-do-mar, arraias e bagres.&nbsp;De acordo com dados do Corpo de Bombeiros, entre 14 de dezembro e 2 de janeiro, foram realizados 8.017 atendimentos envolvendo \u00e1gua-viva no Litoral paranaense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Sesa orienta que os banhistas sigam as recomenda\u00e7\u00f5es dos postos de guarda-vidas e evitem praias com hist\u00f3rico recente de acidentes com \u00e1guas-vivas e caravelas. Em locais rochosos ou com pedras soltas, \u00e9 importante utilizar cal\u00e7ados apropriados e evitar colocar as m\u00e3os em tocas, buracos ou sob pedras. Em rios e lagos \u00e9 preciso aten\u00e7\u00e3o especial durante a pesca, manuseando os peixes com cuidado ao retirar anz\u00f3is e redes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2024\/04\/image-45.png\" alt=\"\" class=\"wp-image-21394\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O que fazer em caso de acidente?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se ocorrer um acidente com animal pe\u00e7onhento, a recomenda\u00e7\u00e3o \u00e9 procurar atendimento m\u00e9dico imediatamente. Todos os servi\u00e7os de sa\u00fade est\u00e3o preparados para avaliar e tratar casos desse tipo, incluindo a indica\u00e7\u00e3o de soroterapia, quando necess\u00e1ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Enquanto aguarda o atendimento algumas medidas podem ser adotadas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u2013 Lave o local da picada com \u00e1gua e sab\u00e3o (exceto em casos de contato com \u00e1guas-vivas ou caravelas).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u2013 Mantenha a pessoa em repouso e com o membro afetado elevado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u2013 Retire acess\u00f3rios como an\u00e9is, pulseiras, rel\u00f3gios e cal\u00e7ados apertados em caso de acidentes nas extremidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u2013 Para acidentes com \u00e1guas-vivas e caravelas, procure o posto de guarda-vidas mais pr\u00f3ximo, aplique vinagre na \u00e1rea afetada, sem esfregar, e utilize compressas geladas com pacotes fechados de gelo. Nunca lave com \u00e1gua doce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u2013 \u00c9 fundamental que a v\u00edtima informe ao profissional de sa\u00fade o m\u00e1ximo de caracter\u00edsticas do animal envolvido no acidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCaso seja poss\u00edvel, levar uma foto do animal ou o pr\u00f3prio animal, se estiver morto, isso ser\u00e1 extremamente \u00fatil para auxiliar no diagn\u00f3stico preciso e na escolha do tratamento adequado\u201d, destacou a bi\u00f3loga Juliana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Em caso de d\u00favidas e orienta\u00e7\u00f5es entre em contato pelos seguintes telefones:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CIATox Paran\u00e1: 08000 410148 (o n\u00famero \u00e9 zero oito mil)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CIATox Londrina: (43) 3371-2244<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CIATox Maring\u00e1: (44) 3011-9127<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CIATox Cascavel: (45) 3321-5261<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Reportagem: AEN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Sa\u00fade (Sesa) faz um alerta \u00e0 popula\u00e7\u00e3o sobre o risco de acidentes com animais pe\u00e7onhentos, tanto terrestres quanto aqu\u00e1ticos, comuns nessa \u00e9poca do ano, de temperaturas mais altas. O per\u00edodo entre dezembro e mar\u00e7o, marcado pela maior movimenta\u00e7\u00e3o de pessoas em regi\u00f5es tur\u00edsticas, de mata e Litoral, coincide com o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[172],"class_list":["post-32602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regional","tag-featured"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/32602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/comments?post=32602"}],"version-history":[{"count":2,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/32602\/revisions"}],"predecessor-version":[{"id":32608,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/32602\/revisions\/32608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/media\/32606"}],"wp:attachment":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/media?parent=32602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/categories?post=32602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/tags?post=32602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}