{"id":4430,"date":"2021-11-10T14:59:18","date_gmt":"2021-11-10T17:59:18","guid":{"rendered":"https:\/\/radiostudiow.com.br\/site\/?p=4430"},"modified":"2025-01-31T15:12:22","modified_gmt":"2025-01-31T18:12:22","slug":"conversao-irregular-de-camioneta-causa-acidente-no-inicio-da-serra-do-leao-na-br-153","status":"publish","type":"post","link":"https:\/\/radiostudiow.com.br\/site\/2021\/11\/10\/conversao-irregular-de-camioneta-causa-acidente-no-inicio-da-serra-do-leao-na-br-153\/","title":{"rendered":"Convers\u00e3o irregular de camioneta causa acidente no in\u00edcio da Serra do Le\u00e3o na BR-153"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A equipe do Corpo de Bombeiros de Uni\u00e3o da Vit\u00f3ria esteve atendendo no meio por volta das 16:10 horas dessa ter\u00e7a-feira, 09 de novembro a um acidente de tr\u00e2nsito no in\u00edcio da Serra Le\u00e3o, na rodovia BR-153.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com informa\u00e7\u00f5es o acidente envolveu uma camioneta Ford\/F4000 com placas da cidade de Cruz Machado, a qual ao tentar fazer uma convers\u00e3o para entrar na contram\u00e3o da marginal que liga \u00e0 rodovia, acabou sendo atingida por uma carreta Scania\/R420 com placas da cidade de Panambi\/RS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a batida, um rapaz acabou ficando ferido. Ele recebeu os primeiros socorros e foi encaminhado para cuidados m\u00e9dicos no hospital Regional. O tr\u00e2nsito ficou lento no local.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2021\/09\/NUTRI-MALLET.jpg\" alt=\"\" class=\"wp-image-3543\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A equipe do Corpo de Bombeiros de Uni\u00e3o da Vit\u00f3ria esteve atendendo no meio por volta das 16:10 horas dessa ter\u00e7a-feira, 09 de novembro a um acidente de tr\u00e2nsito no in\u00edcio da Serra Le\u00e3o, na rodovia BR-153. De acordo com informa\u00e7\u00f5es o acidente envolveu uma camioneta Ford\/F4000 com placas da cidade de Cruz Machado, a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[172],"class_list":["post-4430","post","type-post","status-publish","format-standard","hentry","category-policial","tag-featured"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/4430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/comments?post=4430"}],"version-history":[{"count":1,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/4430\/revisions"}],"predecessor-version":[{"id":4432,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/4430\/revisions\/4432"}],"wp:attachment":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/media?parent=4430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/categories?post=4430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/tags?post=4430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}