{"id":7915,"date":"2022-06-27T09:33:09","date_gmt":"2022-06-27T12:33:09","guid":{"rendered":"https:\/\/radiostudiow.com.br\/site\/?p=7915"},"modified":"2025-01-31T15:10:04","modified_gmt":"2025-01-31T18:10:04","slug":"suposto-caso-de-sequestro-e-registrado-em-sao-mateus-do-sul","status":"publish","type":"post","link":"https:\/\/radiostudiow.com.br\/site\/2022\/06\/27\/suposto-caso-de-sequestro-e-registrado-em-sao-mateus-do-sul\/","title":{"rendered":"Suposto caso de sequestro \u00e9 registrado em S\u00e3o Mateus do Sul"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Militar de S\u00e3o Mateus do Sul foi acionada na tarde de domingo, 26 de junho, na Vila Amaral, em que a solicitante relatou que o ex-genro sequestrou sua filha junto com a neta de um ano de idade. Ela informou aos policiais que\u00a0ambos\u00a0possuem defici\u00eancia auditiva, sendo surdos e mudos, entretanto,\u00a0sua filha\u00a0\u00e9 muito dependente dela e por isso mora com a m\u00e3e at\u00e9 hoje.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2022\/06\/vem_ai.jpg\" alt=\"\" class=\"wp-image-7789\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A solicitante disse que o ex-genro&nbsp;sempre pega a beb\u00ea aos s\u00e1bados e devolve no domingo, entretanto, hoje ao ir devolver a crian\u00e7a, ele agarrou&nbsp;a mulher&nbsp;e a colocou no ve\u00edculo \u00e0 for\u00e7a, sendo que quem viu o acontecido foi seu outro neto de 10 anos de idade, que narrou os mesmos fatos aos policiais e disse ainda que haviam duas outras mulheres junto no ve\u00edculo, as quais tamb\u00e9m s\u00e3o surdas e mudas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com essas informa\u00e7\u00f5es, a equipe da PM deslocou com a solicitante at\u00e9 a casa de&nbsp;uma terceira pessoa, a qual atendeu a equipe e passou a relatar atrav\u00e9s de escrita e sinais que a m\u00e3e da vitima&nbsp;mant\u00e9m&nbsp;a jovem presa dentro de casa, que n\u00e3o deixa&nbsp;ela&nbsp;viver a vida e que&nbsp;desejava ficar junto com&nbsp;o pai de sua filha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os policiais n\u00e3o conseguiram contato com&nbsp;a suposta v\u00edtima, pois n\u00e3o possui celular, e&nbsp;o suposto autor&nbsp;n\u00e3o atendia as liga\u00e7\u00f5es realizadas pela equipe. Os envolvidos estavam em um ve\u00edculo&nbsp;Gol&nbsp;prata, sendo que populares informaram que o ve\u00edculo havia sa\u00eddo sentido a cidade de Irati. Foi relatado ainda pela solicitante que o homem possui parentes na cidade da Lapa, sendo informadas ambas as unidades a respeito do ocorrido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questionado a solicitante se mantinha algum contato com&nbsp;o suposto autor,&nbsp;respondeu que n\u00e3o, apenas quando ele ia buscar a beb\u00ea. Ela disse que&nbsp;sua filha&nbsp;n\u00e3o arrumou nenhuma roupa, e n\u00e3o deu ind\u00edcios de querer sair de casa. Assim sendo, orientada quanto as provid\u00eancias cab\u00edveis e arroladas as testemunhas que alegam que n\u00e3o foi um sequestro, no boletim de ocorr\u00eancia para oitivas posteriores se necess\u00e1rio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/radiostudiow.com.br\/site\/wp-content\/uploads\/2022\/06\/NUTRI-MALLET.jpg\" alt=\"\" class=\"wp-image-7772\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Militar de S\u00e3o Mateus do Sul foi acionada na tarde de domingo, 26 de junho, na Vila Amaral, em que a solicitante relatou que o ex-genro sequestrou sua filha junto com a neta de um ano de idade. Ela informou aos policiais que\u00a0ambos\u00a0possuem defici\u00eancia auditiva, sendo surdos e mudos, entretanto,\u00a0sua filha\u00a0\u00e9 muito dependente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[172],"class_list":["post-7915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-featured"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/7915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/comments?post=7915"}],"version-history":[{"count":2,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/7915\/revisions"}],"predecessor-version":[{"id":7917,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/posts\/7915\/revisions\/7917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/media\/7607"}],"wp:attachment":[{"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/media?parent=7915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/categories?post=7915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiostudiow.com.br\/site\/wp-json\/wp\/v2\/tags?post=7915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}